{"id":1654,"date":"2014-02-03T12:05:56","date_gmt":"2014-02-03T12:05:56","guid":{"rendered":""},"modified":"2026-03-11T09:12:25","modified_gmt":"2026-03-11T14:12:25","slug":"papa-a-religiosos-jovenes-no-ignorois-la-sabiduroa-de-los-ancianos","status":"publish","type":"post","link":"https:\/\/ceas.org.pe\/index.php\/2014\/02\/03\/papa-a-religiosos-jovenes-no-ignorois-la-sabiduroa-de-los-ancianos\/","title":{"rendered":"Papa a religiosos j\u00f3venes: No ignor\u00f3is la sabidur\u00f3a de los ancianos"},"content":{"rendered":"<p>\u00a0<span style=\"text-align: justify;\">El Papa centr\u00f3 su homil\u00eda en el <\/span><span style=\"text-align: justify;\">encuentro con Cristo<\/span><span style=\"text-align: justify;\">. Explic\u00f3 que igual que Mar\u00eda y Jos\u00e9 presentaron a Jes\u00fas en el templo, cada orden religiosa tambi\u00e9n ayuda a encontrarse con \u00c9l.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: justify;\"><span lang=\"ES\">\u00a0<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: justify;\"><span lang=\"ES\">Francisco<\/span><span lang=\"ES\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: justify;\"><i><span lang=\"ES\">\u00abNuestro encuentro con Cristo ha tomado su forma en la Iglesia gracias al carisma de uno de sus testigos. Esto siempre nos sorprende y nos hace dar gracias\u201d.<\/span><\/i><span lang=\"ES\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: justify;\"><span lang=\"ES\">El Papa observ\u00f3 que en la vida consagrada tambi\u00e9n se da un encuentro entre j\u00f3venes y ancianos, entre aquellos que \u00abguardan la ley\u201d y los que, en cambio, ya \u00abson profetas\u201d.<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: justify;\"><span lang=\"ES\">\u00a0<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: justify;\"><span lang=\"ES\">Francisco<\/span><span lang=\"ES\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: justify;\"><i><span lang=\"ES\">\u00abEs bueno que los j\u00f3venes recojan este patrimonio de experiencia y sabidur\u00eda para llevarlo adelante. No para guardarlo en un museo, \u00bfeh? No, no, no. Para llevarlo adelante con los desaf\u00edos que d\u00e9 la vida\u201d. \u00a0<\/span><\/i><span lang=\"ES\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt; text-align: justify;\"><span lang=\"ES\">El Papa concluy\u00f3 que el encuentro con<b> <\/b>Cristo trae alegr\u00eda, y pidi\u00f3 a los religiosos que sea ese el centro de sus vidas.<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\"><i><span lang=\"ES\">Tomado de: Rome Reports del 03\/02\/14<o:p><\/o:p><\/span><\/i><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES\">\u00a0<\/span><\/p>\n<p><a href=\"http:\/\/web.hilo.org.pe\/wp-content\/uploads\/CARISMA.jpg\" target=\"_blank\" rel=\"noopener\">Ver archivo adjunto<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Miles de religiosos llenaron la bas?lica de San Pedro para celebrar con Francisco la Jornada Mundial de la Vida Consagrada.<\/p>\n","protected":false},"author":1,"featured_media":7874,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-1654","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/posts\/1654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/comments?post=1654"}],"version-history":[{"count":1,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/posts\/1654\/revisions"}],"predecessor-version":[{"id":7564,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/posts\/1654\/revisions\/7564"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/media\/7874"}],"wp:attachment":[{"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/media?parent=1654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/categories?post=1654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/tags?post=1654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}