{"id":1642,"date":"2014-01-27T10:42:38","date_gmt":"2014-01-27T10:42:38","guid":{"rendered":""},"modified":"2026-03-11T09:12:26","modified_gmt":"2026-03-11T14:12:26","slug":"arequipa-parroquias-ofrecen-vacaciones-otiles-para-todas-las-edades","status":"publish","type":"post","link":"https:\/\/ceas.org.pe\/index.php\/2014\/01\/27\/arequipa-parroquias-ofrecen-vacaciones-otiles-para-todas-las-edades\/","title":{"rendered":"Arequipa: parroquias ofrecen vacaciones \u00f3tiles para todas las edades"},"content":{"rendered":"<div>Como es usual en los meses de verano, que coinciden con las vacaciones escolares, las parroquias de la Arquidi\u00f3cesis de Arequipa, disponen de amplios programas de Vacaciones \u00datiles, mediante talleres y cursos para ni\u00f1os, j\u00f3venes y adultos en horarios de ma\u00f1ana y tarde.<\/div>\n<div>\u00a0<\/div>\n<div>Para esta oportunidad se ha previsto una gran diversidad de temas de inter\u00e9s para los fieles. Tal es el caso en la Parroquia Esp\u00edritu Santo en Alto Selva Alegre, en donde los peque\u00f1os podr\u00e1n aprender M\u00fasica, T\u00e9cnica Vocal, Piano, Guitarra, Lecto-Escritura, Pintura, etc. Mientras que en la Parroquia San Jos\u00e9 Obrero en La Pampilla, se ofrecen los cursos de M\u00fasica, Futbol, Mini Chef, Danza, Arte y Oratoria. Asimismo en la Parroquia San Miguel de Sim\u00f3n Bol\u00edvar se apertura el curso de Guitarra de lunes a viernes.<\/div>\n<div>\u00a0<\/div>\n<div>Por su parte, Caritas Arequipa ofrece la capacitaci\u00f3n dirigida a madres de familia y j\u00f3venes en Cer\u00e1mica al fr\u00edo, Tejido, Tarjeter\u00eda, Pintura en Tela, Marinera, Danza Moderna, entre otros.<\/div>\n<div>\u00a0<\/div>\n<div>A pesar de que estos espacios acad\u00e9micos y de recreaci\u00f3n deportiva ya se iniciaron, es posible a\u00fan lograr la inscripci\u00f3n y de esa manera dar posibilidad y oportunidad tambi\u00e9n a los adultos, para vivir momentos de confraternidad.<\/div>\n<p><a href=\"http:\/\/web.hilo.org.pe\/wp-content\/uploads\/20140127_ninos talleres.jpg\" target=\"_blank\" rel=\"noopener\">Ver archivo adjunto<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como es usual en los meses de verano, que coinciden con las vacaciones escolares, las parroquias de la Arquidi?cesis de Arequipa, disponen de amplios programas de Vacaciones ?tiles, mediante talleres y cursos para ni?os, j?venes y adultos en horarios de ma?ana y tarde.<\/p>\n","protected":false},"author":1,"featured_media":7932,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-1642","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/posts\/1642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/comments?post=1642"}],"version-history":[{"count":1,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/posts\/1642\/revisions"}],"predecessor-version":[{"id":7576,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/posts\/1642\/revisions\/7576"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/media\/7932"}],"wp:attachment":[{"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/media?parent=1642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/categories?post=1642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/tags?post=1642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}