{"id":1631,"date":"2014-01-21T09:25:16","date_gmt":"2014-01-21T09:25:16","guid":{"rendered":""},"modified":"2026-03-11T09:12:26","modified_gmt":"2026-03-11T14:12:26","slug":"puno-coritas-apoya-encuentros-intergeneracionales","status":"publish","type":"post","link":"https:\/\/ceas.org.pe\/index.php\/2014\/01\/21\/puno-coritas-apoya-encuentros-intergeneracionales\/","title":{"rendered":"Puno: C\u00f3ritas apoya encuentros intergeneracionales"},"content":{"rendered":"<p>\u00a0<\/p>\n<div>Los \u201cEncuentros Intergeneracionales\u201d son considerados como una \u00a0estrategia para fomentar relaciones intergeneracionales de diferentes grupos etarios con el adulto mayor.<\/div>\n<div>\u00a0<\/div>\n<div>Consiste en reuniones activas y muy din\u00e1micas que se desarrollan entre estudiantes de instituciones educativas con adultos mayores de grupos organizados, con un enfoque de respeto de derechos para la prevenci\u00f3n del maltrato, promoci\u00f3n del trato digno y una imagen digna del adulto mayor.<\/div>\n<div>\u00a0<\/div>\n<div>Talleres de sensibilizaci\u00f3n dirigido a adultos mayores, a \u00a0ni\u00f1os de instituciones educativas; y tambi\u00e9n a docentes son algunas de las actividades que se priorizaron dentro de esta iniciativa.<\/div>\n<div>\u00a0<\/div>\n<div>Los temas que se abordaron en los talleres son por ejemplo: Etapas de la vida humana, autovaloraci\u00f3n del adulto mayor, problem\u00e1tica del adulto mayor o los \u00a0factores que contribuyen al buen envejecimiento.<\/div>\n<div>\u00a0<\/div>\n<div>En esta perspectiva los encuentros intergeneracionales en si son veh\u00edculos para la transmisi\u00f3n de conocimientos, donde se genera un espacio de aprendizaje entre el adulto mayor y el ni\u00f1o. Se comparten por ejemplo: saberes sobre las plantas medicinales, la difusi\u00f3n de cuentos tradicionales de la zona o se organizan grupos para promover actividades de reforestaci\u00f3n.<\/div>\n<div>\u00a0<\/div>\n<div>Adem\u00e1s, estos espacios promueven el buen trato y respeto a los adultos mayores, pues los \u00a0ni\u00f1os pueden relacionarse directamente con los ancianos en un clima de confianza, incluso apelando \u00a0sus costumbres., tradiciones, y valores propios.<\/div>\n<div>\u00a0<\/div>\n<div>Para lograr los resultados esperados, se utiliza una metodolog\u00eda participativa para captar la atenci\u00f3n y concentraci\u00f3n de los ni\u00f1os; y del otro, de las personas mayores. Se aplican\u00a0t\u00e9cnicas participativas de animaci\u00f3n y presentaci\u00f3n, socio dramas, trabajos grupales donde interact\u00faan ambas generaciones, dramatizaci\u00f3n de vivencias familiares y juegos recreativos con \u00e9nfasis en valores y con enfoque de derechos<\/div>\n<div>\u00a0<\/div>\n<div>En el proceso de un encuentro intergeneracional, es posible distinguir las capacidades y habilidades que poseen los adultos mayores; adem\u00e1s de la creatividad con que pueden ense\u00f1ar a los ni\u00f1os sus conocimientos. (Fuente: Blog C\u00e1ritas de Puno)<\/div>\n<div>\u00a0<\/div>\n<p><a href=\"http:\/\/web.hilo.org.pe\/wp-content\/uploads\/Encuentros Intergeneraciionales.JPG\" target=\"_blank\" rel=\"noopener\">Ver archivo adjunto<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>C?ritas Puno viene ejecutando el proyecto ?Promoci?n de eventos intergeneracionales entre ni?os (as) de instituciones educativas y adultos nayores rurales para un envejecimiento satisfactorio en la regi?n Puno?, patrocinado por la fundaci?n Christel Wasiek. Estos encuentros permiten generar nuevas posibilidades de relaci?n entre ni?os y adultos mayores, donde se busca crear v?nculos afectivos.<\/p>\n","protected":false},"author":1,"featured_media":7862,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-1631","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/posts\/1631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/comments?post=1631"}],"version-history":[{"count":1,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/posts\/1631\/revisions"}],"predecessor-version":[{"id":7587,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/posts\/1631\/revisions\/7587"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/media\/7862"}],"wp:attachment":[{"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/media?parent=1631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/categories?post=1631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/tags?post=1631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}