{"id":1581,"date":"2013-12-06T08:45:17","date_gmt":"2013-12-06T08:45:17","guid":{"rendered":""},"modified":"2026-03-11T09:12:27","modified_gmt":"2026-03-11T14:12:27","slug":"telegrama-del-papa-por-el-fallecimiento-de-nelson-mandela-defensor-de-la-justicia-y-la-paz","status":"publish","type":"post","link":"https:\/\/ceas.org.pe\/index.php\/2013\/12\/06\/telegrama-del-papa-por-el-fallecimiento-de-nelson-mandela-defensor-de-la-justicia-y-la-paz\/","title":{"rendered":"Telegrama del Papa por el fallecimiento de Nelson Mandela, defensor de la justicia y la paz"},"content":{"rendered":"<p>Al encomendar el alma del difunto a la misericordia infinita de Dios Todopoderoso, el Papa Francisco pide al Se\u00f1or que consuele y fortalezca a todos los que lloran su p\u00e9rdida. <\/p>\n<p>En su mensaje de p\u00e9same el Papa Francisco rinde homenaje al firme compromiso demostrado por Nelson Mandela en la promoci\u00f3n de la dignidad humana de todos los ciudadanos de la naci\u00f3n y en la creaci\u00f3n de una nueva Sud\u00e1frica basada en los firmes cimientos de la no violencia, la reconciliaci\u00f3n y la verdad. <\/p>\n<p>El Papa reza para que el ejemplo del difunto presidente inspire a las generaciones de sudafricanos a poner la justicia y el bien com\u00fan en la vanguardia de sus aspiraciones pol\u00edticas. Con estos sentimientos, el Pont\u00edfice invoca sobre todos el pueblo de Sud\u00e1frica los dones divinos de la paz y la prosperidad. (Fuente: www.news.va)<br \/>\n\u00a0<\/p>\n<p><a href=\"http:\/\/web.hilo.org.pe\/wp-content\/uploads\/juanpabloII-Mandela.JPG\" target=\"_blank\" rel=\"noopener\">Ver archivo adjunto<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Santo Padre Francisco ha escrito un telegrama de p?same al presidente sudafricano, Jacob Zuma, en el que expresa su dolor y tristeza por el fallecimiento del ex presidente Nelson Mandela. El Papa reza por ?l y env?a sus condolencias a toda la familia Mandela, a los miembros del Gobierno y a todo el pueblo de Sud?frica.<\/p>\n","protected":false},"author":1,"featured_media":7848,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-1581","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/posts\/1581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/comments?post=1581"}],"version-history":[{"count":1,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/posts\/1581\/revisions"}],"predecessor-version":[{"id":7637,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/posts\/1581\/revisions\/7637"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/media\/7848"}],"wp:attachment":[{"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/media?parent=1581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/categories?post=1581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/tags?post=1581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}