{"id":1567,"date":"2013-11-29T11:59:43","date_gmt":"2013-11-29T11:59:43","guid":{"rendered":""},"modified":"2026-03-11T09:12:27","modified_gmt":"2026-03-11T14:12:27","slug":"el-papa-francisco-jesos-quiere-que-pienses-por-ti-mismo-fuera-del-pensamiento-uniforme","status":"publish","type":"post","link":"https:\/\/ceas.org.pe\/index.php\/2013\/11\/29\/el-papa-francisco-jesos-quiere-que-pienses-por-ti-mismo-fuera-del-pensamiento-uniforme\/","title":{"rendered":"El Papa Francisco: \u00abJes\u00f3s quiere que pienses por ti mismo, fuera del pensamiento uniforme\u00bb"},"content":{"rendered":"<p>\u00a0<\/p>\n<div style=\"text-align: justify; line-height: normal; margin: 0cm 0cm 12pt\"><b><span style=\"color: black\">29 de noviembre, 2013. (Romereports.com)<\/span><\/b><span style=\"color: black\"> En su Misa en Casa Santa Marta, Francisco explic\u00f3 lo que significa \u201c<b>pensar en cristiano<\/b>\u201d. Dijo que era necesario ver el mundo con la <b>cabeza<\/b> pero tambi\u00e9n con el<b> alma<\/b> y el <b>coraz\u00f3n<\/b>. \u00a0\u00a0<\/span><\/div>\n<div style=\"text-align: justify; line-height: normal; margin: 0cm 0cm 2.5pt\"><b><span style=\"color: black\">PAPA FRANCISCO<\/span><\/b><\/div>\n<div style=\"text-align: justify; line-height: normal; margin: 0cm 0cm 2.5pt\"><i><span style=\"color: black\">\u201c\u00bfCu\u00e1l es el camino que quiere el Se\u00f1or? Siempre con el esp\u00edritu de inteligencia para entender las se\u00f1ales del tiempo. Es bonito pedirle al Se\u00f1or Jes\u00fas esta gracia, que nos env\u00ede su esp\u00edritu de inteligencia, para que nosotros no tengamos un pensamiento d\u00e9bil, no tengamos un pensamiento uniforme y no tengamos un pensamiento seg\u00fan nuestros propios gustos: solamente tengamos un pensamiento seg\u00fan Dios. Con este pensamiento, que es un pensamiento de la mente, del coraz\u00f3n y del alma\u201d.<\/span><\/i><\/div>\n<div style=\"text-align: justify; line-height: normal; margin: 0cm 0cm 2.5pt\">\u00a0<\/div>\n<div style=\"text-align: justify; line-height: normal; margin: 0cm 0cm 2.5pt\"><span style=\"color: black\">El Papa tambi\u00e9n advirti\u00f3 de los peligros del <b>pensamiento uniforme<\/b>, que convierte a las personas en masa <b>sin libertad<\/b>.<\/span><\/div>\n<div style=\"text-align: center; line-height: normal; margin: 0cm 0cm 2.5pt\" align=\"center\">\u00a0<\/div>\n<div style=\"text-align: center; line-height: normal; margin: 0cm 0cm 2.5pt\" align=\"center\">\u00a0<\/div>\n<div style=\"text-align: justify; line-height: normal; margin: 0cm 0cm 2.5pt\"><b><span style=\"color: black\">EXTRACTO DE LA HOMIL\u00cdA<\/span><\/b><\/div>\n<div style=\"text-align: justify; line-height: normal; margin: 0cm 0cm 2.5pt\"><b><span style=\"color: black\">(Fuente, Radio Vaticana)<\/span><\/b><\/div>\n<div style=\"text-align: justify; line-height: normal; margin: 0cm 0cm 2.5pt\"><i><span style=\"color: black\">\u201c\u00c9sta es la gracia que debemos pedir hoy al Se\u00f1or: la capacidad que nos da el Esp\u00edritu Santo para comprender bien los signos de los tiempos\u201d.<\/span><\/i><\/div>\n<div style=\"text-align: justify; line-height: normal; margin: 0cm 0cm 2.5pt\">\u00a0<\/div>\n<div style=\"text-align: justify; line-height: normal; margin: 0cm 0cm 2.5pt\"><i><span style=\"color: black\">\u201cEn el Evangelio, Jes\u00fas no se enoja, pero lo finge cuando los disc\u00edpulos no entienden las cosas. A los de Ema\u00fas dice: \u00a1necios y tardos de coraz\u00f3n. \u00ab\u00a1Oh necios, y tardos de coraz\u00f3n \u201c&#8230; \u00c9l que no entiende las cosas de Dios es una persona as\u00ed. El Se\u00f1or quiere que entendamos lo que sucede: lo que pasa en mi coraz\u00f3n, lo que est\u00e1 pasando en mi vida, lo que sucede en el mundo, en la historia&#8230; \u00bfQu\u00e9 significa esto que est\u00e1 pasando ahora? \u00a1Estos son los signos de los tiempos! En cambio, el esp\u00edritu del mundo nos hace otras propuestas, porque el esp\u00edritu del mundo no nos quiere como pueblo: nos quiere masa, sin pensamiento, sin libertad\u201d.<\/span><\/i><\/div>\n<div style=\"text-align: justify; line-height: normal; margin: 0cm 0cm 2.5pt\">\u00a0<\/div>\n<div style=\"text-align: justify; line-height: normal; margin: 0cm 0cm 2.5pt\"><i><span style=\"color: black\">\u00abEl pensamiento uniforme, el mismo pensamiento, el pensamiento d\u00e9bil, un pensamiento tan extendido. El esp\u00edritu del mundo no quiere que nos preguntemos delante de Dios: \u00abPero \u00bfpor qu\u00e9 esto, por qu\u00e9 aquello, \u00bfpor qu\u00e9 sucede esto?\u201d. O incluso nos propone un pensamiento pr\u00eat-\u00e0-porter, de acuerdo a nuestros propios gustos: \u201cYo pienso como me da la gana\u201d. Esto para ellos est\u00e1 bien, dicen&#8230; Pero lo que el esp\u00edritu del mundo no quiere es lo que Jes\u00fas nos pide: \u00a1el libre pensamiento, el pensamiento de un hombre y de una mujer que son parte del pueblo de Dios, y la salvaci\u00f3n es precisamente \u00e9sta! Piensen en los profetas&#8230; \u201cT\u00fa no eras mi pueblo, ahora te digo \u201cpueblo m\u00edo\u201d: as\u00ed dice el Se\u00f1or. Y \u00e9sta es la salvaci\u00f3n: hacernos pueblo, pueblo de Dios, para tener libertad\u201d.<\/span><\/i><\/div>\n<div style=\"text-align: justify; line-height: normal; margin: 0cm 0cm 2.5pt\">\u00a0<\/div>\n<div style=\"text-align: justify; line-height: normal; margin: 0cm 0cm 2.5pt\"><i><span style=\"color: black\">\u00ab\u00bfCu\u00e1l es el camino que quiere el Se\u00f1or? Siempre con el esp\u00edritu de inteligencia para comprender los signos de los tiempos. Es hermoso pedir al Se\u00f1or Jes\u00fas esta gracia, que nos env\u00ede el esp\u00edritu de comprensi\u00f3n, para que no tengamos un pensamiento d\u00e9bil, un pensamiento uniforme, y un pensamiento seg\u00fan los propios gustos: sino un pensamiento como lo quiere Dios. Con este pensamiento, que es un pensamiento de mente, de coraz\u00f3n y de alma. Con este pensamiento, que es un don del Esp\u00edritu Santo, buscar que es lo que quieren decir las cosas y entender bien los signos de los tiempos\u201d.\u00a0<\/span><\/i><\/div>\n<p><a href=\"http:\/\/web.hilo.org.pe\/wp-content\/uploads\/ESPIRITU CRISTIANO.jpg\" target=\"_blank\" rel=\"noopener\">Ver archivo adjunto<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En su Misa en Casa Santa Marta, Francisco explic? lo que significa ?pensar en cristiano?. Dijo que era necesario ver el mundo con la cabeza pero tambi?n con el alma y el coraz?n.<\/p>\n","protected":false},"author":1,"featured_media":7855,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-1567","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/posts\/1567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/comments?post=1567"}],"version-history":[{"count":1,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/posts\/1567\/revisions"}],"predecessor-version":[{"id":7651,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/posts\/1567\/revisions\/7651"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/media\/7855"}],"wp:attachment":[{"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/media?parent=1567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/categories?post=1567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/tags?post=1567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}