{"id":1541,"date":"2013-11-14T07:11:09","date_gmt":"2013-11-14T07:11:09","guid":{"rendered":""},"modified":"2026-03-11T09:12:27","modified_gmt":"2026-03-11T14:12:27","slug":"advierten-que-mayoroa-de-trabajadoras-del-hogar-perciben-sueldo-por-debajo-del-monimo-vital","status":"publish","type":"post","link":"https:\/\/ceas.org.pe\/index.php\/2013\/11\/14\/advierten-que-mayoroa-de-trabajadoras-del-hogar-perciben-sueldo-por-debajo-del-monimo-vital\/","title":{"rendered":"Advierten que mayor\u00f3a de trabajadoras del hogar perciben sueldo por debajo del m\u00f3nimo vital"},"content":{"rendered":"<p>\n\u201cSeg\u00fan el Ministerio de Trabajo y Promoci\u00f3n del Empleo (MTPE), alrededor 404,127 personas se dedican al trabajo del hogar remunerado, de las cuales el 85% percibe sueldos inferiores al m\u00ednimo vital y solo el 22.4% se encontrar\u00edan aseguradas en EsSalud, pese a que la norma lo exige\u201d, se\u00f1al\u00f3 Vega Luna, al presentar el Informe de Adjunt\u00eda: \u201cLas Trabajadoras del Hogar en el Per\u00fa. Supervisi\u00f3n a los sectores encargados de la promoci\u00f3n y defensa de sus derechos\u201d.<br \/>\nPor su parte, la Adjunta para los Derechos de la Mujer, Carolina Garc\u00e9s, afirm\u00f3 que es necesario que el Congreso de la Rep\u00fablica modifique la Ley N\u00ba 27986 a fin de que contemple el derecho a la remuneraci\u00f3n m\u00ednima vital de las trabajadoras del hogar, la exigencia de un contrato escrito para la prestaci\u00f3n de sus servicios, as\u00ed como un trato no discriminatorio en lo referido a vacaciones, gratificaciones, sobretasa por laborar en d\u00edas feriados y compensaci\u00f3n por tiempo de servicios (CTS).<br \/>\nGarc\u00e9s destac\u00f3, adem\u00e1s, la necesidad de realizar acciones coordinadas entre las entidades p\u00fablicas con competencias en la materia, por lo que exhort\u00f3 al MTPE y al Ministerio de la Mujer y Poblaciones Vulnerables a liderar la articulaci\u00f3n de esfuerzos dirigidos a fortalecer la difusi\u00f3n de los derechos de este sector de la poblaci\u00f3n.<br \/>\n\u201cLamentablemente, la desprotecci\u00f3n que hoy enfrentan las trabajadoras del hogar se conecta con graves problemas sociales como el racismo, el sexismo y la pobreza. Por ello, para hacer frente a esta situaci\u00f3n, adem\u00e1s de la adopci\u00f3n de medidas legislativas y de pol\u00edticas p\u00fablicas por parte del Estado, se requiere el compromiso de todos los ciudadanos y ciudadanas\u201d, concluy\u00f3 Vega Luna.<br \/>\nPara realizar el mencionado informe, la Defensor\u00eda del Pueblo supervis\u00f3 5 ministerios con competencias en la materia, 3 organismos p\u00fablicos (SUNAT, ESSALUD y ONP), adem\u00e1s de solicitar informaci\u00f3n a la Municipalidad Metropolitana de Lima y a veinte municipalidades distritales de Lima Metropolitana, con el fin de conocer las acciones desarrolladas en la protecci\u00f3n de los derechos de las trabajadoras del hogar.<strong> (Fuente http:\/\/www.defensoria.gob.pe)<br \/>\n<\/strong><br \/>\n\u00a0<\/p>\n<p><a href=\"http:\/\/web.hilo.org.pe\/wp-content\/uploads\/trabajadores.del-hogar.jpg\" target=\"_blank\" rel=\"noopener\">Ver archivo adjunto<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Defensor del Pueblo (e), Eduardo Vega Luna, advirti? hoy que la gran mayor?a de trabajadoras del hogar en el Per? perciben remuneraciones por debajo del m?nimo vital, enfrentan extensas jornadas de trabajo y no tienen acceso a la seguridad social, por lo que exhort? a las instituciones competentes a adoptar medidas para revertir esta situaci?n.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-1541","post","type-post","status-publish","format-standard","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/posts\/1541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/comments?post=1541"}],"version-history":[{"count":1,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/posts\/1541\/revisions"}],"predecessor-version":[{"id":7677,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/posts\/1541\/revisions\/7677"}],"wp:attachment":[{"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/media?parent=1541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/categories?post=1541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ceas.org.pe\/index.php\/wp-json\/wp\/v2\/tags?post=1541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}